{"id":32,"count":1,"description":"","link":"https:\/\/gregladen.com\/blog\/tag\/red-queen\/","name":"Red Queen","slug":"red-queen","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gregladen.com\/blog\/wp-json\/wp\/v2\/tags\/32"}],"collection":[{"href":"https:\/\/gregladen.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gregladen.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gregladen.com\/blog\/wp-json\/wp\/v2\/posts?tags=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}